{"id":120,"count":1,"description":"","link":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/","name":"dental disease cats","slug":"dental-disease-cats","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>dental disease cats Archives - Coal Creek Animal Hospital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dental disease cats Archives - Coal Creek Animal Hospital\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/\" \/>\n<meta property=\"og:site_name\" content=\"Coal Creek Animal Hospital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/tag\\\/dental-disease-cats\\\/\",\"url\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/tag\\\/dental-disease-cats\\\/\",\"name\":\"dental disease cats Archives - Coal Creek Animal Hospital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/tag\\\/dental-disease-cats\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/tag\\\/dental-disease-cats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"dental disease cats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/\",\"name\":\"Coal Creek Animal Hospital\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coalcreekanimalhospital.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dental disease cats Archives - Coal Creek Animal Hospital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/","og_locale":"en_US","og_type":"article","og_title":"dental disease cats Archives - Coal Creek Animal Hospital","og_url":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/","og_site_name":"Coal Creek Animal Hospital","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/","url":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/","name":"dental disease cats Archives - Coal Creek Animal Hospital","isPartOf":{"@id":"https:\/\/www.coalcreekanimalhospital.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coalcreekanimalhospital.com\/blog\/tag\/dental-disease-cats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.coalcreekanimalhospital.com\/blog\/"},{"@type":"ListItem","position":2,"name":"dental disease cats"}]},{"@type":"WebSite","@id":"https:\/\/www.coalcreekanimalhospital.com\/blog\/#website","url":"https:\/\/www.coalcreekanimalhospital.com\/blog\/","name":"Coal Creek Animal Hospital","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coalcreekanimalhospital.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.coalcreekanimalhospital.com\/blog\/wp-json\/wp\/v2\/tags\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coalcreekanimalhospital.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.coalcreekanimalhospital.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.coalcreekanimalhospital.com\/blog\/wp-json\/wp\/v2\/posts?tags=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}